
{"id":5834,"date":"2024-09-25T12:50:26","date_gmt":"2024-09-25T12:50:26","guid":{"rendered":"https:\/\/workwiseavocats.com\/workwise-avocats-nouvelle-boutique-parisienne-dediee-au-droit-social-des-affaires\/"},"modified":"2024-10-01T14:51:36","modified_gmt":"2024-10-01T14:51:36","slug":"workwise-avocats-nouvelle-boutique-parisienne-dediee-au-droit-social-des-affaires","status":"publish","type":"post","link":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/","title":{"rendered":"Workwise Avocats, a new Paris boutique dedicated to business employment law"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;5645&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;100%&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; el_class=&#8221;justify&#8221;]\n<h2>The business employment law landscape in Paris has been enriched by the arrival of Workwise Avocats, a new specialist boutique founded by four lawyers. C\u00e9cile Zoro, Philippe Cazello, Jocelyn Hagneau and Emmanuel Maudet, all formerly at Clifford Chance, are combining their expertise to create this structure dedicated to business employment law.<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;35&#8243;][vc_column_text css=&#8221;&#8221; el_class=&#8221;justify&#8221; text_direction=&#8221;default&#8221;]Workwise Avocats targets a diverse client base, including French and international companies, investment fund management companies and senior executives.<\/p>\n<p>Based at 91, rue du Faubourg-Saint-Honor\u00e9, Workwise Avocats advises French and international companies, investment funds and executives on all their employment law issues, with particular expertise in corporate reorganisations, the employment aspects of equity transactions and high-stakes individual and collective litigation. The team is also developing strong relationships in support of business law firms on employment law issues.[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#002643&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; el_class=&#8221;justify&#8221; text_direction=&#8221;default&#8221;]\n<h3>Founders with complementary backgrounds<\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#002643&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;h3&#8243; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;C\u00e9cile Zoro&#8221; url=&#8221;\/en\/team\/cecile-zoro\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;&#8221; el_class=&#8221;justify&#8221; text_direction=&#8221;default&#8221;]A graduate of IEP and the University of Bordeaux, as well as DJCE from the University of Poitiers, she began her career in 2000 at Freshfields Br\u00fcckhaus Deringer before joining Bredin Prat, where she was appointed counsel, and then Clifford Chance in 2018. She has extensive expertise in complex M&amp;A transactions and advises on specific issues relating to protected executives, managers and employees.[\/vc_column_text][vc_row_inner column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#002643&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;h3&#8243; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Philippe Cazello&#8221; url=&#8221;\/en\/team\/philippe-cazello\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;&#8221; el_class=&#8221;justify&#8221; text_direction=&#8221;default&#8221;]Philippe holds a Master&#8217;s degree in Employment Law from the University of Paris I and an LL.M. from the University of Cologne. He joined Clifford Chance in 2011 and was appointed counsel in 2021. Philippe is a recognised expert in corporate reorganisation and individual and collective litigation, both judicial and administrative.[\/vc_column_text][vc_row_inner column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#002643&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;h3&#8243; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Jocelyn Hagneau&#8221; url=&#8221;\/en\/team\/jocelyn-hagneau\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;&#8221; el_class=&#8221;justify&#8221; text_direction=&#8221;default&#8221;]A graduate of the University of Cergy Pontoise and the University of Paris I, he has worked at Clifford Chance since 2011. His expertise covers restructurings, business transfers, remuneration issues, criminal labour law and CSR, as well as executive departures.[\/vc_column_text][vc_row_inner column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#002643&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;h3&#8243; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;Emmanuel Maudet&#8221; url=&#8221;\/en\/team\/emmanuel-maudet\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;&#8221; el_class=&#8221;justify&#8221; text_direction=&#8221;default&#8221;]A graduate of Universit\u00e9 Paris ll, he joined Clifford Chance in 2018 after working for nearly four years in a corporate environment with the Richemont Group. He advises on day-to-day employment law issues, as well as on high-stakes reorganisations and negotiated departures of managers and executives.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221; animate=&#8221;yes&#8221; delay=&#8221;200&#8243;][image_with_animation image_url=&#8221;5697&#8243; image_size=&#8221;medium&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;60%&#8221; img_link=&#8221;https:\/\/lemondedudroit.fr\/vie-des-cabinets\/94743-workwise-avocats-nouvelle-boutique-parisienne-dediee-droit-social-affaires.html&#8221;][nectar_btn size=&#8221;medium&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Read the article&#8221; url=&#8221;https:\/\/lemondedudroit.fr\/vie-des-cabinets\/94743-workwise-avocats-nouvelle-boutique-parisienne-dediee-droit-social-affaires.html&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-5834","post","type-post","status-publish","format-standard","category-life-at-the-firm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workwise Avocats, a new Paris boutique dedicated to business employment law - Workwise Avocats<\/title>\n<meta name=\"description\" content=\"The business employment law landscape in Paris has been enriched by the arrival of Workwise Avocats, a new specialist boutique founded by four lawyers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workwise Avocats, a new Paris boutique dedicated to business employment law - Workwise Avocats\" \/>\n<meta property=\"og:description\" content=\"The business employment law landscape in Paris has been enriched by the arrival of Workwise Avocats, a new specialist boutique founded by four lawyers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/\" \/>\n<meta property=\"og:site_name\" content=\"Workwise Avocats\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T12:50:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T14:51:36+00:00\" \/>\n<meta name=\"author\" content=\"Matt\u00e9o Menard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matt\u00e9o Menard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\\\/\"},\"author\":{\"name\":\"Matt\u00e9o Menard\",\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/#\\\/schema\\\/person\\\/8d2e5eedc260d77f16e794194e8c80b9\"},\"headline\":\"Workwise Avocats, a new Paris boutique dedicated to business employment law\",\"datePublished\":\"2024-09-25T12:50:26+00:00\",\"dateModified\":\"2024-10-01T14:51:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\\\/\"},\"wordCount\":2488,\"articleSection\":[\"Firm news\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\\\/\",\"url\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\\\/\",\"name\":\"Workwise Avocats, a new Paris boutique dedicated to business employment law - Workwise Avocats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/#website\"},\"datePublished\":\"2024-09-25T12:50:26+00:00\",\"dateModified\":\"2024-10-01T14:51:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/#\\\/schema\\\/person\\\/8d2e5eedc260d77f16e794194e8c80b9\"},\"description\":\"The business employment law landscape in Paris has been enriched by the arrival of Workwise Avocats, a new specialist boutique founded by four lawyers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workwise Avocats, a new Paris boutique dedicated to business employment law\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/\",\"name\":\"Workwise Avocats\",\"description\":\"Avocats en Droit du travail Corporate - Paris\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/#\\\/schema\\\/person\\\/8d2e5eedc260d77f16e794194e8c80b9\",\"name\":\"Matt\u00e9o Menard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b084871ba89adbcd27e4c719f61b11427552d53ea44c3af072d5b1641809138?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b084871ba89adbcd27e4c719f61b11427552d53ea44c3af072d5b1641809138?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b084871ba89adbcd27e4c719f61b11427552d53ea44c3af072d5b1641809138?s=96&d=mm&r=g\",\"caption\":\"Matt\u00e9o Menard\"},\"url\":\"https:\\\/\\\/workwiseavocats.com\\\/en\\\/author\\\/matteo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workwise Avocats, a new Paris boutique dedicated to business employment law - Workwise Avocats","description":"The business employment law landscape in Paris has been enriched by the arrival of Workwise Avocats, a new specialist boutique founded by four lawyers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/","og_locale":"en_US","og_type":"article","og_title":"Workwise Avocats, a new Paris boutique dedicated to business employment law - Workwise Avocats","og_description":"The business employment law landscape in Paris has been enriched by the arrival of Workwise Avocats, a new specialist boutique founded by four lawyers.","og_url":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/","og_site_name":"Workwise Avocats","article_published_time":"2024-09-25T12:50:26+00:00","article_modified_time":"2024-10-01T14:51:36+00:00","author":"Matt\u00e9o Menard","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Matt\u00e9o Menard","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/#article","isPartOf":{"@id":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/"},"author":{"name":"Matt\u00e9o Menard","@id":"https:\/\/workwiseavocats.com\/en\/#\/schema\/person\/8d2e5eedc260d77f16e794194e8c80b9"},"headline":"Workwise Avocats, a new Paris boutique dedicated to business employment law","datePublished":"2024-09-25T12:50:26+00:00","dateModified":"2024-10-01T14:51:36+00:00","mainEntityOfPage":{"@id":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/"},"wordCount":2488,"articleSection":["Firm news"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/","url":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/","name":"Workwise Avocats, a new Paris boutique dedicated to business employment law - Workwise Avocats","isPartOf":{"@id":"https:\/\/workwiseavocats.com\/en\/#website"},"datePublished":"2024-09-25T12:50:26+00:00","dateModified":"2024-10-01T14:51:36+00:00","author":{"@id":"https:\/\/workwiseavocats.com\/en\/#\/schema\/person\/8d2e5eedc260d77f16e794194e8c80b9"},"description":"The business employment law landscape in Paris has been enriched by the arrival of Workwise Avocats, a new specialist boutique founded by four lawyers.","breadcrumb":{"@id":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/workwiseavocats.com\/en\/workwise-avocats-a-new-paris-boutique-dedicated-to-business-employment-law\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/workwiseavocats.com\/en\/"},{"@type":"ListItem","position":2,"name":"Workwise Avocats, a new Paris boutique dedicated to business employment law"}]},{"@type":"WebSite","@id":"https:\/\/workwiseavocats.com\/en\/#website","url":"https:\/\/workwiseavocats.com\/en\/","name":"Workwise Avocats","description":"Avocats en Droit du travail Corporate - Paris","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/workwiseavocats.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/workwiseavocats.com\/en\/#\/schema\/person\/8d2e5eedc260d77f16e794194e8c80b9","name":"Matt\u00e9o Menard","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7b084871ba89adbcd27e4c719f61b11427552d53ea44c3af072d5b1641809138?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7b084871ba89adbcd27e4c719f61b11427552d53ea44c3af072d5b1641809138?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b084871ba89adbcd27e4c719f61b11427552d53ea44c3af072d5b1641809138?s=96&d=mm&r=g","caption":"Matt\u00e9o Menard"},"url":"https:\/\/workwiseavocats.com\/en\/author\/matteo\/"}]}},"_links":{"self":[{"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/posts\/5834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/comments?post=5834"}],"version-history":[{"count":4,"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/posts\/5834\/revisions"}],"predecessor-version":[{"id":5838,"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/posts\/5834\/revisions\/5838"}],"wp:attachment":[{"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/media?parent=5834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/categories?post=5834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/workwiseavocats.com\/en\/wp-json\/wp\/v2\/tags?post=5834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}